{"id":58916,"count":1,"description":"","link":"https:\/\/www.mauritiustimes.com\/mt\/tag\/trade-deal\/","name":"Trade Deal","slug":"trade-deal","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags\/58916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts?tags=58916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}