{"id":50949,"count":1,"description":"","link":"https:\/\/www.mauritiustimes.com\/mt\/tag\/overwhelming\/","name":"Overwhelming","slug":"overwhelming","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags\/50949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts?tags=50949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}