{"id":412,"count":1,"description":"","link":"https:\/\/www.mauritiustimes.com\/mt\/tag\/femmes-et-politique-presidente-de-la-republique\/","name":"Femmes et Politique Pr\u00e9sidente de la R\u00e9publique","slug":"femmes-et-politique-presidente-de-la-republique","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags\/412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts?tags=412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}