{"id":4088,"count":1,"description":"","link":"https:\/\/www.mauritiustimes.com\/mt\/tag\/electoral-reform-rodrigues\/","name":"Electoral Reform\u00a0\u00a0\u00a0 Rodrigues","slug":"electoral-reform-rodrigues","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags\/4088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts?tags=4088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}