{"id":8966,"date":"2017-09-29T15:52:48","date_gmt":"2017-09-29T11:52:48","guid":{"rendered":"http:\/\/mauritiustimes.com\/mt\/?p=8966"},"modified":"2017-09-29T15:52:48","modified_gmt":"2017-09-29T11:52:48","slug":"lair-du-temps","status":"publish","type":"post","link":"https:\/\/www.mauritiustimes.com\/mt\/lair-du-temps\/","title":{"rendered":"L&#8217;air du temps"},"content":{"rendered":"<p style=\"text-align: center;\"><em>Il y a un \u00ab tipping moment \u00bb o\u00f9 tout bascule et tout \u00e9chappe aux meilleurs efforts du pouvoir en place de redresser une barque qui d\u00e9rive et tangue, d\u00e9j\u00e0 vou\u00e9e \u00e0 une perdition prochaine<\/em><!--more--><\/p>\n<p>Parmi les grandes nations du monde occidental, les particularit\u00e9s des \u00c9tats-Unis au plan politique et ses \u00e9quilibres de pouvoir n&#8217;en font pas un mod\u00e8le de d\u00e9mocratie dont les le\u00e7ons et les analyses sont exportables ou m\u00eame compr\u00e9hensibles ailleurs dans le monde.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8967\" data-permalink=\"https:\/\/www.mauritiustimes.com\/mt\/lair-du-temps\/ramgoolam-navin-050110-medium\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2017\/09\/Ramgoolam-Navin-050110-Medium.jpg?fit=900%2C675&amp;ssl=1\" data-orig-size=\"900,675\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Ramgoolam Navin 050110 (Medium)\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2017\/09\/Ramgoolam-Navin-050110-Medium.jpg?fit=640%2C480&amp;ssl=1\" class=\" wp-image-8967 aligncenter\" src=\"https:\/\/i0.wp.com\/mauritiustimes.com\/mt\/wp-content\/uploads\/2017\/09\/Ramgoolam-Navin-050110-Medium-300x225.jpg?resize=474%2C355\" alt=\"\" width=\"474\" height=\"355\" srcset=\"https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2017\/09\/Ramgoolam-Navin-050110-Medium.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2017\/09\/Ramgoolam-Navin-050110-Medium.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2017\/09\/Ramgoolam-Navin-050110-Medium.jpg?w=900&amp;ssl=1 900w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>Pourtant, au regard de la derni\u00e8re campagne \u00e9lectorale, aux cris et chants d\u00e9cha\u00een\u00e9s de \u00ab lock her up! \u00bb ou de \u00ab crooked Hilary \u00bb, aliment\u00e9e par un d\u00e9sir de changement, une d\u00e9fiance profonde sinon m\u00eame un rejet brutal des \u00e9lites enracin\u00e9es \u00e0 Washington et des slogans au populisme ravageur, l&#8217;incroyable Mr Trump va se hisser au pouvoir. Au grand dam de ces \u00e9lites lib\u00e9rales qui n&#8217;ont pas vu venir cette vague de rejet plus que d&#8217;acceptation, Trump n&#8217;ayant au fond, avec un grand flair politique, que captur\u00e9 \u00ab l&#8217;air du temps \u00bb contre ces \u00e9lites coupables, aux yeux d&#8217;une fraction importante de l\u2019Am\u00e9rique profonde, de tous les m\u00e9faits tels que la mondialisation, le terrorisme, l\u2019immigration et d\u2019\u00eatre obnubil\u00e9es par leurs combines et strat\u00e9gies de survie dans les coulisses du pouvoir \u00e0 Washington.<\/p>\n<p>Qu&#8217;importe si Trump, bien embarrass\u00e9 de construire son fameux mur pay\u00e9 par les mexicains, se r\u00e9v\u00e8le incapable de mener \u00e0 bon port une l\u00e9gislation-clef pour amender ou remplacer le \u00ab Obamacare \u00bb tant d\u00e9cri\u00e9 durant sa campagne \u00e9lectorale, qu\u2019importe qu&#8217;il ait b\u00e9n\u00e9fici\u00e9 du soutien tacite ou explicite de Putin, l&#8217;homme est au pouvoir.<\/p>\n<p>L&#8217;air du temps et la condamnation des \u00e9lites politiques trop \u00e9loign\u00e9es des pr\u00e9occupations citoyennes ont fait de l&#8217;improbable une r\u00e9alit\u00e9. Qu&#8217;importe s&#8217;il a recrut\u00e9 et limog\u00e9 des dizaines de subalternes \u00e0 la Maison Blanche, qu&#8217;importe l&#8217;impression de chaos, ses tweets d\u00e9sopilants et ses fanfaronnades publiques, qu&#8217;importe ses agressions hebdomadaires contre les m\u00e9dias accus\u00e9s de faire en permanence du \u00abfake news\u00bb contre son pouvoir autoritaire, m\u00eame l\u2019Am\u00e9rique profonde d\u00e9sorient\u00e9e par toutes ces controverses qui s&#8217;empilent, doivent vivre avec les cons\u00e9quences de leur choix \u00e9lectoral: un \u00e9nergum\u00e8ne politique \u00e0 la Maison Blanche issu de \u00ab l&#8217;air du temps \u00bb.<\/p>\n<p style=\"text-align: center;\"><strong>t<\/strong><strong>erreau fertile<\/strong><\/p>\n<p>Dans le contexte des pays aux traditions plus anciennes en Europe, la mondialisation, la d\u00e9localisation des entreprises, la mont\u00e9e de la pr\u00e9carit\u00e9 et du ch\u00f4mage, l&#8217;immigration non-ma\u00eetris\u00e9e, l&#8217;afflux des r\u00e9fugi\u00e9s, les \u00e9pisodes d&#8217;attentats terroristes d&#8217;inspiration salafiste ou jihadiste, ont offert un terreau fertile aux mouvements populistes cherchant \u00e0 surfer les raidissements d&#8217;une soci\u00e9t\u00e9 en mal-\u00eatre.<\/p>\n<p>C&#8217;est en partie sur ce fond de repli nationaliste frileux et du rejet des \u00e9lites politiques et celles financi\u00e8res de la City que le Royaume-Uni a fini par c\u00e9der au Brexit sans vraiment appr\u00e9hender toutes les cons\u00e9quences ni saisir tous les \u00e9l\u00e9ments du prix \u00e0 payer pour l\u2019\u00e9conomie et le quotidien des Britanniques. Eux aussi vont devoir vivre avec les cons\u00e9quences de leur choix, issu de l&#8217;air du temps politique.<\/p>\n<p>Dans l&#8217;Europe continentale, de la Gr\u00e8ce \u00e0 l&#8217;Espagne, les populistes nationalistes, depuis une bonne vingtaine d\u2019ann\u00e9es, tentent de surfer ces vagues d\u2019inqui\u00e9tude et de restructurations des \u00e9conomies engag\u00e9es dans la mondialisation, n\u2019\u00e9pargnant m\u00eame pas les pays scandinaves les moins expos\u00e9s. Seule l&#8217;Allemagne, ayant fait de la stabilit\u00e9, des compromis et du devenir partag\u00e9 des vertus in\u00e9branlables, voit l&#8217;inamovible Angela Merkel, mod\u00e8le de simplicit\u00e9 et de probit\u00e9, r\u00e9sister \u00e0 l&#8217;usure du temps et voguer tranquillement de mandat en mandat.<\/p>\n<p>En France, la tentation du populisme nationaliste et du rejet des \u00e9lites, symbolis\u00e9 par le Front National, a ratiss\u00e9 large dans les peurs et les ins\u00e9curit\u00e9s grandissantes des Fran\u00e7ais \u00e9c\u0153ur\u00e9s par le sentiment d&#8217;alternances gauche-droite toutes impuissantes face \u00e0 Bruxelles ou \u00e0 la mondialisation financi\u00e8re. Seul un programme \u00e9conomique t\u00e2tonnant entre sortie de l&#8217;euro et retour du franc et une performance d\u00e9sastreuse de Marine Le Pen face au n\u00e9ophyte Macron, ont retenu les digues, m\u00eame si en retour, une fraction des Fran\u00e7ais s\u2019inqui\u00e8tent des reformes structurelles \u00e0 venir dans l\u2019\u00e8re du mouvement en marche. L&#8217;air du temps, mine de rien, a balay\u00e9 dans un m\u00eame rejet droite, gauche et lepenistes et boulevers\u00e9 la donne politique traditionnelle en France. On ne peut pr\u00e9dire si cette transformation inattendue mais dans l&#8217;air du temps, sera durable; ce qu&#8217;on sait avec certitude c&#8217;est que le pays devra vivre avec.<\/p>\n<p>Y a-t-il donc un \u00ab air du temps \u00bb politique, d&#8217;autant plus difficile \u00e0 cerner ou \u00e0 d\u00e9finir que les racines souterraines qui la sous-tendent peuvent \u00eatre complexes, sp\u00e9cifiques aux institutions, traditions et cultures de chaque pays ? Pourtant, on pourra difficilement nier que cet ind\u00e9finissable \u00ab air du temps \u00bb avait quelque chose \u00e0 voir avec le raz-de-mar\u00e9e qui a balay\u00e9 un Congress trop dynastique et a port\u00e9 Modi aux cimes en Inde, il y a trois ans. Ajoutons que l&#8217;air du temps a contribu\u00e9 singuli\u00e8rement \u00e0 porter les improbables Trump et Macron, dans diff\u00e9rentes circonstances, au fa\u00eete du pouvoir.<\/p>\n<p style=\"text-align: center;\"><strong>l<\/strong><strong>e d\u00e9sir du changement<\/strong><\/p>\n<p>Il serait possible d&#8217;y voir l&#8217;expression d&#8217;une d\u00e9saffection circonstancielle ou d&#8217;une exasp\u00e9ration momentan\u00e9e avec le <em>status quo<\/em> pr\u00e9valant ou avec l&#8217;alternance politique propos\u00e9e. Si cette exasp\u00e9ration trouve un exutoire m\u00eame moyennement cr\u00e9dible, le d\u00e9sir du changement peut d\u00e9jouer les pronostics les plus savants en se transformant en une vague souvent souterraine et impr\u00e9visible, mais qu\u2019on ne peut arr\u00eater.<\/p>\n<p>Quelles qu&#8217;en soient les cons\u00e9quences et le tribut \u00e0 payer, on pourrait m\u00eame consid\u00e9rer qu&#8217;il y a un \u00ab tipping moment \u00bb o\u00f9 tout bascule et tout \u00e9chappe aux meilleurs efforts du pouvoir en place de redresser une barque qui d\u00e9rive et tangue, d\u00e9j\u00e0 vou\u00e9e \u00e0 une perdition prochaine.<\/p>\n<p>Avec un syst\u00e8me \u00e9lectoral qui favorise les alliances et amplifie les changements d&#8217;humeur de la population, Maurice a bien connu des grandes manifestations de cet \u00ab air du temps \u00bb, force souvent souterraine mais irr\u00e9pressible pour le changement. A bien des \u00e9gards, quatre des cinq derni\u00e8res consultations \u00e9lectorales depuis 1995, peuvent l\u00e9gitimement se placer chacune dans \u00ab l&#8217;air du temps \u00bb qui a balay\u00e9 toutes les combinaisons d&#8217;alliances de grands partis qui ont tent\u00e9 vainement d&#8217;y r\u00e9sister: MSM-RMM-PMSD, PT-PMSD, MSM-MMM et PT-MMM.<\/p>\n<p>Tous les partis, au pouvoir comme dans l&#8217;opposition, en sont parfaitement conscients, l&#8217;imaginaire collectif se nourrissant d&#8217;une somme de non-dits, de ranc\u0153urs accumul\u00e9es, de libert\u00e9s malmen\u00e9es, de loufoqueries et d&#8217;erreurs strat\u00e9giques du pouvoir, le d\u00e9samour avoisine dangereusement la d\u00e9saffection et le rejet.<\/p>\n<p>Le mauricien lambda n&#8217;est pas du genre \u00e0 descendre dans les rues, il est m\u00eame suffisamment rus\u00e9 pour laisser planer l\u2019incertitude, il peut ruer sur les r\u00e9seaux sociaux mais il attend plut\u00f4t son heure. C&#8217;est peut-\u00eatre cela, en pr\u00e9sence d&#8217;une alternative cr\u00e9dible, qui donnera corps \u00e0 la vague du changement qui est capable de balayer les calculs, les tactiques, les alliances, les exercices de communication et les strat\u00e9gies des plus avis\u00e9es.<\/p>\n<p>L&#8217;air du temps\u00a0: il vaut mieux s&#8217;en m\u00e9fier!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a un \u00ab tipping moment \u00bb o\u00f9 tout bascule et tout \u00e9chappe aux meilleurs efforts du pouvoir en place de redresser une barque qui d\u00e9rive et tangue, d\u00e9j\u00e0 vou\u00e9e \u00e0 une perdition prochaine<\/p>\n","protected":false},"author":61,"featured_media":8967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,25],"tags":[3151,101,95,92,213,318,5855,72,1459,5857,5856,2519,155],"class_list":["post-8966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-latest-news","category-politics","tag-angela-merkel","tag-brexit","tag-donald-trump","tag-emmanuel-macron","tag-marine-le-pen","tag-msm-mmm","tag-msm-rmm-pmsd","tag-narendra-modi","tag-obamacare","tag-pt-mmm","tag-pt-pmsd","tag-s-callikan","tag-vladimir-putin"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2017\/09\/Ramgoolam-Navin-050110-Medium.jpg?fit=900%2C675&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QzSF-2kC","_links":{"self":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts\/8966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/comments?post=8966"}],"version-history":[{"count":0,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts\/8966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/media\/8967"}],"wp:attachment":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/media?parent=8966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/categories?post=8966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags?post=8966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}