{"id":800,"date":"2011-02-11T06:51:41","date_gmt":"2011-02-11T06:51:41","guid":{"rendered":"http:\/\/mauritiustimes.com\/mt\/2011\/02\/11\/jean-baptiste-placca-16\/"},"modified":"2020-04-15T15:08:54","modified_gmt":"2020-04-15T11:08:54","slug":"jean-baptiste-placca-16","status":"publish","type":"post","link":"https:\/\/www.mauritiustimes.com\/mt\/jean-baptiste-placca-16\/","title":{"rendered":"Egypte\u00a0: Journalistes en danger"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #000000;\">\u00a0<u>Chronique de Jean-Baptiste Placca<\/u><\/span><!--more--><\/p>\n<p><span style=\"color: #000000;\"><strong>Qui donc accepterait de se passer des images en provenance d\u2019Egypte\u00a0? Celles des huit premiers jours, lorsque les manifestations \u00e9taient comme un immense festival, un \u00ab\u00a0Woodstock\u00a0\u00bb de la libert\u00e9 et de la d\u00e9mocratie, mais aussi celles, \u00e9difiantes, de l\u2019entr\u00e9e en sc\u00e8ne des partisans du pr\u00e9sident Moubarak, avec\u00a0les <em>Baltagueiya<\/em>, ces jeunes hommes de main, recrut\u00e9s pour semer la terreur.<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Outre leurs concitoyens, qu\u2019ils ont agress\u00e9s, pi\u00e9tin\u00e9s, bless\u00e9s par centaines, \u00e0 <em>Tahrir Square<\/em>, ces <em>Baltagueiya<\/em> cherchaient tout particuli\u00e8rement \u00e0 terroriser les journalistes des m\u00e9dias \u00e9trangers. Le pr\u00e9sident Moubarak a eu beau se dire afflig\u00e9 par ces sc\u00e8nes de violence, cela n\u2019a pas emp\u00each\u00e9 son vice-pr\u00e9sident de d\u00e9signer, aussit\u00f4t apr\u00e8s, les cha\u00eenes satellitaires comme responsables des troubles, juste apr\u00e8s les Fr\u00e8res musulmans\u00a0!<\/span><\/p>\n<p><span style=\"color: #000000;\">Si ceux qui ont attaqu\u00e9 les journalistes avaient eu besoin d\u2019un ordre de mission, ils pouvaient ais\u00e9ment le trouver dans le discours officiel. Pour le pouvoir, le probl\u00e8me n\u2019est pas l\u2019absence de d\u00e9mocratie en Egypte, mais le fait d\u2019en parler au monde. Comme s\u2019il suffisait de faire silence sur l\u2019arbitraire et les vexations que d\u00e9nonce la foule des manifestants pour que le pays retrouve sa qui\u00e9tude.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>L\u2019information, une denr\u00e9e de premi\u00e8re n\u00e9cessit\u00e9<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Pendant que le chef de l\u2019Etat multiplie les promesses de r\u00e9formes, le harc\u00e8lement ne faiblit pas sur les journalistes \u00e9gyptiens qui refusent de se mettre au service de la propagande officielle. L\u2019un d\u2019eux, atteint mercredi par une balle anonyme, a d\u2019ailleurs succomb\u00e9, le vendredi 4 f\u00e9vrier.<\/span><\/p>\n<p><span style=\"color: #000000;\">Se confiant \u00e0 une star de la t\u00e9l\u00e9vision am\u00e9ricaine, Hosni Moubarak a laiss\u00e9 entendre que Barack Obama ne comprend rien au peuple \u00e9gyptien. Il aurait pu ajouter que ce peuple n\u2019a pas besoin de libert\u00e9 et de d\u00e9mocratie mais d\u2019un dirigeant autoritaire qui, apr\u00e8s trente ans de pouvoir, doit \u00eatre cru sur parole, lorsqu\u2019il promet des r\u00e9formes.<\/span><\/p>\n<p><span style=\"color: #000000;\">Vous en souvenez-vous\u00a0? Ben Ali aussi rendait les m\u00e9dias \u00e9trangers responsables du soul\u00e8vement dans son pays. Un de ses ambassadeurs a m\u00eame affirm\u00e9 que derri\u00e8re les manifestants se cachaient, tenez-vous bien, des Bolch\u00e9viks\u00a0! Cela s\u2019appelle l\u2019angoisse de la perte du pouvoir.<\/span><\/p>\n<p><span style=\"color: #000000;\">Dans notre monde moderne, l\u2019information est une denr\u00e9e de premi\u00e8re n\u00e9cessit\u00e9. Aucun peuple ne peut accepter d\u2019en \u00eatre sevr\u00e9. Et les journalistes, pour \u00eatre si souvent ind\u00e9sirables, n\u2019en sont pas moins utiles. Aux dirigeants \u00e9gyptiens, comme \u00e0 tous les pouvoirs vacillants en qu\u00eate de bouc \u00e9missaire, on a envie de dire\u00a0: ne faites pas tirer sur les journalistes\u00a0! Vous en avez eu besoin hier, vous en aurez probablement encore besoin demain\u00a0!<\/span><br \/>\n<span style=\"color: #000000;\">\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Jean-Baptiste Placca<br \/>\n<\/strong><\/span><span style=\"color: #000000;\">MFI<\/span><\/p>\n<hr \/>\n<p><span style=\"color: #008080;\"><em>* Published in print edition on 11 February 2011<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Chronique de Jean-Baptiste Placca<\/p>\n","protected":false},"author":284,"featured_media":6560,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28],"tags":[23552,432,19238,23551,23444],"class_list":["post-800","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-world-affairs","tag-baltagueiya","tag-barack-obama","tag-jean-baptiste-placca","tag-journalistes","tag-tahrir-square"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2016\/12\/MT-Logokk.jpg?fit=1200%2C880&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QzSF-cU","_links":{"self":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts\/800","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/users\/284"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/comments?post=800"}],"version-history":[{"count":0,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts\/800\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/media\/6560"}],"wp:attachment":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/media?parent=800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/categories?post=800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags?post=800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}