{"id":27299,"date":"2020-05-29T07:28:17","date_gmt":"2020-05-29T03:28:17","guid":{"rendered":"http:\/\/www.mauritiustimes.com\/mt\/?p=27299"},"modified":"2020-05-29T07:28:17","modified_gmt":"2020-05-29T03:28:17","slug":"la-realite-des-ressources","status":"publish","type":"post","link":"https:\/\/www.mauritiustimes.com\/mt\/la-realite-des-ressources\/","title":{"rendered":"La r\u00e9alit\u00e9 des ressources"},"content":{"rendered":"<p><span style=\"color: #000080;\"><strong>By Nita Chicooree-Mercier<\/strong><\/span><!--more--><\/p>\n<p><span style=\"color: #000000;\">Un peu partout, il y a consensus sur le fait que le monde navigue dans le m\u00eame bateau et qu&#8217;\u00e0 force de prendre l&#8217;eau, il s&#8217;est mis \u00e0 tanguer sur un oc\u00e9an ballott\u00e9 par les vents hostiles. Ici et ailleurs, les capitaines se d\u00e9m\u00e8nent comme des diables pour mener leur barque \u00e0 bon port.<\/span><\/p>\n<p><span style=\"color: #000000;\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"27309\" data-permalink=\"https:\/\/www.mauritiustimes.com\/mt\/la-realite-des-ressources\/plantations-legumes-a-maurice\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2020\/05\/Plantations-l%C3%A9gumes-%C3%A0-Maurice.jpg?fit=1200%2C675&amp;ssl=1\" data-orig-size=\"1200,675\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Plantations l\u00e9gumes \u00e0 Maurice\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2020\/05\/Plantations-l%C3%A9gumes-%C3%A0-Maurice.jpg?fit=640%2C360&amp;ssl=1\" class=\"aligncenter size-full wp-image-27309\" src=\"https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2020\/05\/Plantations-l%C3%A9gumes-%C3%A0-Maurice.jpg?resize=640%2C360&#038;ssl=1\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2020\/05\/Plantations-l%C3%A9gumes-%C3%A0-Maurice.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2020\/05\/Plantations-l%C3%A9gumes-%C3%A0-Maurice.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2020\/05\/Plantations-l%C3%A9gumes-%C3%A0-Maurice.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2020\/05\/Plantations-l%C3%A9gumes-%C3%A0-Maurice.jpg?resize=768%2C432&amp;ssl=1 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/span><\/p>\n<p><span style=\"color: #000000;\">Ici, la gestion de peu de ressources dont dispose l&#8217;\u00eele est une pr\u00e9occupation majeure des uns et des autres. C&#8217;est dans cet esprit qu&#8217;on se permet de nous adresser au minist\u00e8re des Utilit\u00e9s publiques pour faire remplacer un tuyau rouill\u00e9 qui fuit sur la route de la colline \u00e0 la Pointe aux Canonniers. Plusieurs habitants du quartier ont appel\u00e9 le 170, jusqu&#8217;\u00e0 pr\u00e9sent, et au bout d&#8217;un mois, il y a eu comme r\u00e9paration un bricolage avec du caoutchouc pour limiter les d\u00e9g\u00e2ts. Le tuyau pourri fuit \u00e0 cinq endroits et l&#8217;eau coule joyeusement jour et nuit. Le camion poubelle a eu la mauvaise id\u00e9e de rouler sur le tuyau pourri et la fuite a repris de plus belle. La solution est de remplacer ce tuyau tout simplement et d&#8217;\u00e9viter ce gaspillage que tout le monde constate avec regret depuis deux mois. C&#8217;est ahurissant !<\/span><\/p>\n<p><span style=\"color: #000000;\">D&#8217;autre part, toute la population gagnerait \u00e0 une campagne de sensibilisation sur l&#8217;utilisation de l&#8217;eau \u00e0 usage domestique. A \u00e9viter le robinet grand ouvert sans interruption dans l&#8217;\u00e9vier de la cuisine et dans la salle de bain. En Afrique du Sud, les h\u00f4tels rappellent aux visiteurs de passage que l&#8217;eau est une denr\u00e9e pr\u00e9cieuse dans le pays et recommandent de l&#8217;utiliser avec parcimonie. Ici, outre la construction d&#8217;h\u00f4tels \u00e0 gogo, trop nombreux le long des c\u00f4tes, certains ont dot\u00e9 chaque bungalow d&#8217;une piscine priv\u00e9e et ont exig\u00e9 une fermeture de route \u00e0 Trou-aux-Biches, par exemple, pour cr\u00e9er un lieu exclusif entre touristes de luxe. Une attention exag\u00e9r\u00e9e qui \u00e9tonne les visiteurs de passage, reflet d&#8217;un orgueil d\u00e9mesur\u00e9 centr\u00e9 sur un &#8216;entre-nous&#8217; qu&#8217;affectionnent les auteurs de cette id\u00e9e sortie de leur chapeau un beau jour pour r\u00e9investir les profits de la compagnie.<\/span><\/p>\n<p><span style=\"color: #000000;\">Les Europ\u00e9ens ont cette tendance f\u00e2cheuse d&#8217;ouvrir grand le robinet pendant toute la dur\u00e9e de la douche ou devant le lavabo matin et soir, de traiter une \u00e9nergie comme un objet mis \u00e0 leur disposition pour un libre usage. C&#8217;est un gaspillage qu&#8217;on peut \u00e9viter par un petit panneau dans la salle de bain des chambres d&#8217;h\u00f4tel invitant les futurs visiteurs \u00e0 respecter un usage mod\u00e9r\u00e9 de l&#8217;eau. Ils comprendront car les touristes d&#8217;aujourd&#8217;hui n&#8217;adh\u00e8rent pas \u00e0 ce comportement de seigneurs sur les terres exotiques qui ont nourri ceux qui pensent leur faire plaisir. Une prise de conscience \u00e9galement aupr\u00e8s des habitants \u00e9viterait l&#8217;insouciance des cigales en temps d&#8217;abondance et les lamentations lors des p\u00e9riodes s\u00e8ches.<\/span><\/p>\n<p><span style=\"color: #000000;\">L&#8217;orientation des p\u00eacheurs vers l&#8217;\u00e9levage des poissons face \u00e0 une r\u00e9duction des revenus est un de ces exemples de voie de sortie lorsque les difficult\u00e9s s&#8217;amoncellent. Ils ne pourront qu&#8217;\u00eatre b\u00e9n\u00e9ficiaires d&#8217;une initiative innovante que repr\u00e9sente ce type de micro entreprise. Cela permet de garder le pied marin sur mer et d&#8217;assurer sur terre une continuit\u00e9 de leur activit\u00e9 par un investissement lucratif qui trouvera toujours preneurs sur le march\u00e9 local. Vivoter au jour le jour entra\u00eene des cons\u00e9quences qui demandent \u00e0 \u00eatre revues \u00e0 la longue.<\/span><\/p>\n<p><span style=\"color: #000000;\">A peine trois semaines apr\u00e8s le confinement la difficult\u00e9 de s&#8217;approvisionner en l\u00e9gumes s&#8217;est fait sentir chez les v\u00e9g\u00e9tariens purs et d&#8217;autres qui le sont \u00e0 80-90%. Compte-tenu des prix prohibitifs affich\u00e9s dans les supermarch\u00e9s (quand c&#8217;\u00e9tait affich\u00e9!) qui ont grandement profit\u00e9 de la situation en tant que seuls vendeurs, les gens ont vite trouv\u00e9 la solution en s&#8217;approvisionnant directement chez les cultivateurs ou dans les petites \u00e9choppes le long des routes. Cette entorse \u00e0 la r\u00e8gle a suscit\u00e9 quelques commentaires avec photos \u00e0 l&#8217;appui. Les queues interminables et l&#8217;offre r\u00e9duite des l\u00e9gumes dans les supermarch\u00e9s ont refroidi un bon nombre de personnes. Il n&#8217;est pas question pour les <em>veggies <\/em>et autres de se tourner vers les morceaux congel\u00e9s qu&#8217;offrent en abondance les rayons des supermarch\u00e9s.<\/span><\/p>\n<p><span style=\"color: #000000;\">Les terres inexploit\u00e9es pourront servir \u00e0 d\u00e9velopper l&#8217;agriculture par les planteurs tandis que s&#8217;exprime davantage la n\u00e9cessit\u00e9 de mettre \u00e0 la disposition des particuliers les terrains abandonn\u00e9s en friche couverts de plantes sauvages, \u00e9pineuses, lianes et utilis\u00e9s comme d\u00e9potoirs pour objets encombrants dans les villages et les quartiers r\u00e9sidentiels le long des c\u00f4tes. C&#8217;est une pratique courante qui gagnerait \u00e0 \u00eatre r\u00e9pandue. Tr\u00e8s souvent les propri\u00e9taires r\u00e9sident ailleurs dans l&#8217;\u00eele ou \u00e0 l&#8217;\u00e9tranger et consentent en tout bon sens \u00e0 laisser les voisins cultiver les terres. Il incombe au minist\u00e8re de l&#8217;Agriculture et le <em>District Councils<\/em> de mettre sur pied ce type d&#8217;exploitation des terres qui existe dans d&#8217;autres pays. Il suffit de r\u00e9pertorier les terrains et de prendre contact avec les propri\u00e9taires, et aussi, de mettre les terres de l&#8217;Etat \u00e0 la disposition des cultivateurs en attendant que se pr\u00e9cisent d&#8217;autres usages bien-intentionn\u00e9s des autorit\u00e9s. Les propri\u00e9taires n&#8217;ont rien \u00e0 perdre, et l&#8217;Etat non plus. Ce sera un plus dans un projet accentu\u00e9 par la pand\u00e9mie de se diriger vers l&#8217;autosuffisance alimentaire.<\/span><\/p>\n<p><span style=\"color: #000000;\">La plantation de courgettes &#8211; dont un vol de 250 kilos dans un champ annonc\u00e9 parmi d&#8217;autres vols de l\u00e9gumes &#8211; semble destin\u00e9e aux supermarch\u00e9s et h\u00f4tels. Ce l\u00e9gume est inexistant sur le march\u00e9 local; est tr\u00e8s pris\u00e9 dans la cuisine m\u00e9diterran\u00e9enne et en Europe, et le populariser davantage ajouterait de la vari\u00e9t\u00e9 et du go\u00fbt \u00e0 la cuisine locale.<\/span><\/p>\n<p><span style=\"color: #000000;\">Le constat d&#8217;une interruption de fabrication de fromage de ch\u00e8vre par quelques Italiens pour les besoins de leur restaurant et magasin suscite une r\u00e9flexion une fois qu&#8217;on a d\u00e9gust\u00e9 le lait de ch\u00e8vre distribu\u00e9 par un propri\u00e9taire de cabris d\u00e8s le d\u00e9but du confinement. Pourquoi ne pas d\u00e9velopper une fabrication artisanale \u00e0 plus grande \u00e9chelle qui pourrait satisfaire l&#8217;app\u00e9tit d&#8217;une client\u00e8le restreinte \u00e0 ce jour mais qui pourrait s&#8217;\u00e9largir au fil des ann\u00e9es\u00a0? Elargir l&#8217;offre et go\u00fbter autre chose que celui affich\u00e9 sur les grands panneaux publicitaires flattant &#8216;le go\u00fbt de l&#8217;\u00eele Maurice&#8217; depuis des ann\u00e9es, un fromage sal\u00e9 et pas terrible comme go\u00fbt. La fabrication de fromage ne rel\u00e8ve pas de la grande technologie, que l&#8217;on sache. On ne peut que se r\u00e9jouir du grand projet d&#8217;autosuffisance pour l&#8217;heure en esp\u00e9rant que l&#8217;intention sera suivie des actes concrets.<\/span><\/p>\n<p><span style=\"color: #000000;\">La d\u00e9tresse et la pauvret\u00e9 resurgissent de plus en plus, les vols de l\u00e9gumes se multiplient. Une faim qui a gagn\u00e9 chiens errants et chats marrons ronge les personnes en situation pr\u00e9caire. Se fait sentir \u00e9galement une impatience \u00e0 se remettre au travail et une lassitude d&#8217;un enfermement qui perdure et qui comprime les libert\u00e9s. L&#8217;adh\u00e9sion du grand public aux mesures prises par le Gouvernement a \u00e9t\u00e9 totale. On s&#8217;interroge n\u00e9anmoins sur le grand d\u00e9ploiement des gabelous dimanche dernier sur les routes. Dans le nord, \u00e9tait-ce pour coller une amende d&#8217;un montant hallucinant aux \u00e9ventuels pigeons \u00e0 plumer ? Cam\u00e9ras de surveillance et contraventions tous azimuts pour entorses au code de la route, une mesure pour remplir les caisses du gouvernement des ann\u00e9es 2007-2014 en imitant une mesure fran\u00e7aise de l&#8217;\u00e9poque avec, en prime, dans le <em>package<\/em>, le mod\u00e8le tr\u00e8s classe de la montre Rolex.<\/span><\/p>\n<p><span style=\"color: #000000;\">La covid a eu l&#8217;effet d\u00e9vastateur \u00e0 travers le monde de vider les caisses de l&#8217;Etat et les poches des contribuables \u00e0 faibles revenus. Avec une couronne d&#8217;\u00e9pines sur la t\u00eate, le monde tourne en rond dans une passion quasi christique. Mais chaque crise ouvre les vannes de la connaissance en science, m\u00e9decine et technologie et suscite de grandes passions d&#8217;exploration et de d\u00e9couverte. La r\u00e9alit\u00e9, c&#8217;est que la solution viendra non d&#8217;une quelconque entit\u00e9 juch\u00e9e au ciel mais des ressources qui d\u00e9coulent des \u00e9nergies dont dispose la terre, les mati\u00e8res premi\u00e8res et de la passion d&#8217;innover et de cr\u00e9er qui anime les esprits.<\/span><\/p>\n<hr \/>\n<p><span style=\"color: #008080;\">* Published in print edition on 29 May 2020<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>By Nita Chicooree-Mercier<\/p>\n","protected":false},"author":23,"featured_media":27309,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[27],"tags":[20427,23494,25333,25334,170,1290],"class_list":["post-27299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-society","tag-agriculture","tag-autosuffisance-alimentaire","tag-detresse-et-pauvrete","tag-gestion-de-ressources","tag-nita-chicooree-mercier","tag-society"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2020\/05\/Plantations-l%C3%A9gumes-%C3%A0-Maurice.jpg?fit=1200%2C675&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QzSF-76j","_links":{"self":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts\/27299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/comments?post=27299"}],"version-history":[{"count":0,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts\/27299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/media\/27309"}],"wp:attachment":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/media?parent=27299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/categories?post=27299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags?post=27299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}