{"id":1667,"date":"2012-05-18T07:52:55","date_gmt":"2012-05-18T07:52:55","guid":{"rendered":"http:\/\/mauritiustimes.com\/mt\/2012\/05\/18\/jean-baptiste-placca-54\/"},"modified":"2019-10-02T10:13:36","modified_gmt":"2019-10-02T06:13:36","slug":"jean-baptiste-placca-54","status":"publish","type":"post","link":"https:\/\/www.mauritiustimes.com\/mt\/jean-baptiste-placca-54\/","title":{"rendered":"Le \u00ab changement \u00bb\u00a0: Pour l\u2019Afrique aussi\u2026"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"line-height: 12pt; margin: 0in 0in 0pt; text-align: center;\"><span style=\"color: #000000;\"><span style=\"text-decoration: underline;\"><span lang=\"FR\" style=\"font-family: Verdana; mso-bidi-font-family: Arial; mso-ansi-language: FR;\"><span style=\"font-size: small;\">Chronique de Jean-Baptiste Placca<\/span><\/span><\/span> <span style=\"text-decoration: underline;\"><span lang=\"FR\" style=\"font-family: Verdana; mso-bidi-font-family: Arial; mso-ansi-language: FR;\"><span style=\"font-size: small;\"><br \/>\n<\/span><\/span><\/span><!--more--><\/span><\/p>\n<h4 class=\"MsoNormal\" style=\"line-height: 12pt; margin: 0in 0in 0pt; text-align: center;\"><span style=\"color: #000000;\"><strong><em><span lang=\"FR\" style=\"font-family: Verdana; mso-bidi-font-family: Arial; mso-ansi-language: FR;\"><span style=\"font-size: small;\">L\u2019\u00e9lection de Fran\u00e7ois Hollande peut avoir, en Afrique, une vertu p\u00e9dagogique : dans l\u2019isoloir, les peuples se rendent ma\u00eetres de leur destin. Et lorsque le peuple a parl\u00e9, il faut simplement avoir l\u2019\u00e9l\u00e9gance de s\u2019\u00e9clipser <\/span><\/span><\/em><\/strong><\/span><\/h4>\n<p class=\"MsoNormal\" style=\"line-height: 12pt; margin: 0in 0in 0pt;\"><span lang=\"FR\" style=\"font-family: Verdana; color: #000000;\"><span style=\"font-size: small;\">\u00a0<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 12pt; margin: 0in 0in 0pt;\"><span lang=\"FR\" style=\"font-family: Verdana; color: #000000;\"><span style=\"font-size: small;\">Vous ne pouvez imaginer avec quelle intensit\u00e9 l\u2019Afrique a v\u00e9cu le deuxi\u00e8me tour de la pr\u00e9sidentielle en France ! Avec, au soir du 6\u00a0mai, ce d\u00e9nouement qui valait mille feux d\u2019artifice. Oui, la d\u00e9mocratie a, d\u00e9finitivement, quelque chose de magique\u00a0!<\/span><\/span><\/p>\n<p style=\"line-height: 12pt; margin: 0in 0in 0pt;\"><span lang=\"FR\" style=\"font-family: Verdana; color: #000000;\"><span style=\"font-size: small;\">\u00a0<\/span><\/span><\/p>\n<p style=\"line-height: 12pt; margin: 0in 0in 0pt;\"><span lang=\"FR\" style=\"font-family: Verdana; color: #000000;\"><span style=\"font-size: small;\">Et merci d\u2019offrir aux peuples africains de vivre, m\u00eame par procuration, des grands moments \u00e9lectoraux comme celui-l\u00e0\u00a0! Deux mois \u00e0 peine apr\u00e8s l\u2019alternance au S\u00e9n\u00e9gal, l\u2019\u00e9lection de Fran\u00e7ois Hollande peut avoir, en Afrique, une vertu p\u00e9dagogique\u00a0: dans l\u2019isoloir, les peuples se rendent ma\u00eetres de leur destin. Et lorsque le peuple a parl\u00e9, il faut simplement avoir l\u2019\u00e9l\u00e9gance de s\u2019\u00e9clipser.<br \/>\nCette chronique est la derni\u00e8re. Rassurez-vous\u00a0: Fran\u00e7ois Hollande n\u2019y est pour rien\u00a0! Je n\u2019\u00e9tais, ici, qu\u2019un passant. Mais, ici ou ailleurs, il faudra continuer \u00e0 forger la conscience citoyenne, partout en Afrique. Tous mes chemins me m\u00e8neront toujours vers vous\u00a0!<br \/>\n<\/span><\/span><\/p>\n<p style=\"line-height: 12pt; margin: 0in 0in 0pt; text-align: center;\"><span style=\"color: #000000;\"><strong><span lang=\"FR\" style=\"font-family: Verdana; mso-bidi-font-family: Arial;\"><span style=\"font-size: small;\">Fran\u00e7ois Hollande va-t-il traquer ces r\u00e9seaux politico-mafieux\u00a0?<\/span><\/span><\/strong><\/span><\/p>\n<p style=\"line-height: 12pt; margin: 0in 0in 0pt;\"><span lang=\"FR\" style=\"font-family: Verdana; color: #000000;\"><br \/>\n<span style=\"font-size: small;\">Avez-vous remarqu\u00e9 que les pouvoirs les plus arrogants, dans notre Afrique, sont toujours ceux qui survivent par la fraude \u00e9lectorale et mille ruses\u00a0? De cette impunit\u00e9 \u00e9lectorale naissent toutes les autres formes d\u2019impunit\u00e9, la corruption, la violence, la gabegie\u2026<br \/>\nC\u2019est la m\u00eame arrogance qui pousse ce responsable du parti au pouvoir dans un pays d\u2019Afrique centrale \u00e0 reprocher aux opposants de se r\u00e9jouir de l\u2019engagement de Fran\u00e7ois Hollande \u00e0 n\u2019accepter aucune \u00e9lection frauduleuse et \u00e0 ne cautionner la corruption nulle part. Sous pr\u00e9texte que cette opposition se serait offusqu\u00e9e, par le pass\u00e9, de l\u2019ing\u00e9rence des dirigeants fran\u00e7ais dans la vie politique de leur pays, on voudrait leur interdire d\u2019esp\u00e9rer quoi que ce soit du nouveau chef de l\u2019Etat fran\u00e7ais.<br \/>\nIl faudra pourtant bien que Fran\u00e7ois Hollande trouve le moyen de traquer tous ces r\u00e9seaux politico-mafieux qui, depuis la France, se sont employ\u00e9, depuis un demi-si\u00e8cle, \u00e0 imposer aux peuples leurs dirigeants, ou en tout cas \u00e0 aider ceux-ci \u00e0 se maintenir au pouvoir, y compris h\u00e9r\u00e9ditairement. Les Africains ne demandent pas \u00e0 la France de les d\u00e9barrasser de ces dirigeants. Non\u00a0! Mais comme il serait suffisant de ne rien faire pour contrarier les efforts que les peuples eux-m\u00eames d\u00e9ploient pour se soustraire de ces mains indignes\u00a0!<br \/>\nSi les ministres fran\u00e7ais ne peuvent d\u00e9noncer les fraudes \u00e9lectorales, qu\u2019ils s\u2019abstiennent au moins d\u2019en minimiser l\u2019ampleur, surtout lorsque des observateurs cr\u00e9dibles et m\u00eame les Etats-Unis d\u00e9noncent ces fraudes. Et que des personnalit\u00e9s politiques fran\u00e7aises n\u2019aillent plus jeter \u00e0 la face des peuples d\u2019Afrique qu\u2019ils ne sont pas m\u00fbrs pour la d\u00e9mocratie, ou pas entr\u00e9s dans l\u2019Histoire. Ce qui revient au m\u00eame.<\/span><\/span><\/p>\n<p style=\"line-height: 12pt; margin: 0in 0in 0pt;\"><span lang=\"FR\" style=\"font-family: Verdana; color: #000000;\"><span style=\"font-size: small;\">\u00a0<\/span><\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 12pt; margin: 0in 0in 0pt;\"><span style=\"font-size: small; color: #000000;\"><strong><span lang=\"FR\" style=\"font-family: Verdana; mso-bidi-font-family: Arial; mso-ansi-language: FR;\">Jean-Baptiste Placca<br \/>\n<\/span><\/strong><span lang=\"FR\" style=\"font-family: Verdana; mso-bidi-font-family: Arial; mso-ansi-language: FR;\">MFI<\/span><\/span><\/p>\n<hr \/>\n<p><em>* Published in print edition on 18 May 2012<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chronique de Jean-Baptiste Placca<\/p>\n","protected":false},"author":284,"featured_media":6560,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28],"tags":[19239,98,19238],"class_list":["post-1667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-world-affairs","tag-etat-francais","tag-francois-hollande","tag-jean-baptiste-placca"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2016\/12\/MT-Logokk.jpg?fit=1200%2C880&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QzSF-qT","_links":{"self":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts\/1667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/users\/284"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/comments?post=1667"}],"version-history":[{"count":0,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts\/1667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/media\/6560"}],"wp:attachment":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/media?parent=1667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/categories?post=1667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags?post=1667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}