{"id":1526,"date":"2012-02-24T08:24:06","date_gmt":"2012-02-24T08:24:06","guid":{"rendered":"http:\/\/mauritiustimes.com\/mt\/2012\/02\/24\/jean-baptiste-placca-45\/"},"modified":"2019-11-24T17:35:42","modified_gmt":"2019-11-24T13:35:42","slug":"jean-baptiste-placca-45","status":"publish","type":"post","link":"https:\/\/www.mauritiustimes.com\/mt\/jean-baptiste-placca-45\/","title":{"rendered":"L\u2019int\u00e9gration ou la fiert\u00e9 nationale"},"content":{"rendered":"<h5 style=\"margin: 0in 0in 0pt; text-align: center;\"><span lang=\"FR\" style=\"font-family: Verdana;\"><span style=\"text-decoration: underline;\"><span style=\"font-size: small;\"><span style=\"color: #000000; text-decoration: underline;\"><span style=\"color: #ff0000; text-decoration: underline;\">Chronique de Jean-Baptiste Placca<\/span> <br style=\"mso-special-character: line-break;\" \/><\/span><\/span><\/span><\/span><\/h5>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>\u00ab\u00a0Air Afrique n\u2019a pas disparu parce qu\u2019elle \u00e9tait un mauvais projet, non\u00a0! La lib\u00e9ralisation du ciel africain, sans un minimum de r\u00e8gles de sauvegarde pour prot\u00e9ger cet outil d\u2019int\u00e9gration, a donn\u00e9 le coup de gr\u00e2ce \u00e0 une compagnie d\u00e9j\u00e0 fragilis\u00e9e par l\u2019immixtion des Etats dans sa gestion\u2026\u00a0\u00bb<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Une semaine avant d\u2019endosser son costume de pr\u00e9sident en exercice de la C\u00e9d\u00e9ao, le chef de l\u2019Etat ivoirien ent\u00e9rinait la cr\u00e9ation d\u2019une compagnie a\u00e9rienne, Air C\u00f4te d\u2019Ivoire, cens\u00e9e combler le vide laiss\u00e9 par la compagnie nationale Air Ivoire, maintes fois d\u00e9c\u00e9d\u00e9e, mille et une fois ressuscit\u00e9e. En vain\u00a0!<\/span><\/p>\n<p><span style=\"color: #000000;\">Au-del\u00e0 de la gestion, souvent hasardeuse, c\u2019est la taille m\u00eame de ces petites compagnies nationales qui hypoth\u00e8que leur viabilit\u00e9. Tenez donc\u00a0! L\u2019infime partie de la flotte de Delta Airlines, que l\u2019on peut apercevoir chaque jour sur le tarmac de l\u2019a\u00e9roport d\u2019Atlanta est bien plus importante que les avions de toutes les compagnies africaines r\u00e9unies. Malgr\u00e9 cela, Delta a jug\u00e9 utile de s\u2019allier \u00e0 Air France-KLM et \u00e0 treize autres compagnies, pour survivre et offrir \u00e0 sa client\u00e8le du choix et de la flexibilit\u00e9.<\/span><\/p>\n<p><span style=\"color: #000000;\">Que l\u2019on nous dise donc par quel miracle Air C\u00f4te d\u2019Ivoire va pouvoir survivre, l\u00e0 o\u00f9 Air Gabon, Air S\u00e9n\u00e9gal International, Cameroon Airlines et tant d\u2019autres aventures solitaires ont \u00e9chou\u00e9\u00a0! Dans le cimeti\u00e8re des compagnies a\u00e9riennes, on trouve aussi, h\u00e9las, Air Afrique. Une des meilleures r\u00e9alisations jamais initi\u00e9es par l\u2019Afrique ind\u00e9pendante. La multinationale a f\u00e9d\u00e9r\u00e9 le continent, au-del\u00e0 de la douzaine de pays actionnaires. L\u2019acte pos\u00e9, le 28\u00a0mars 1961, par les chefs d\u2019Etat africains en cr\u00e9ant Air Afrique est d\u2019autant plus remarquable que c\u2019est exactement ce que tentent de faire, aujourd\u2019hui, les plus grandes compagnies de la plan\u00e8te.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Si l\u2019on se replie sur soi<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Air Afrique n\u2019a pas disparu parce qu\u2019elle \u00e9tait un mauvais projet, non\u00a0! La lib\u00e9ralisation du ciel africain, sans un minimum de r\u00e8gles de sauvegarde pour prot\u00e9ger cet outil d\u2019int\u00e9gration, a donn\u00e9 le coup de gr\u00e2ce \u00e0 une compagnie d\u00e9j\u00e0 fragilis\u00e9e par l\u2019immixtion des Etats dans sa gestion et par l\u2019incurie d\u2019une partie de son personnel.<\/span><br \/>\n<span style=\"color: #000000;\">L\u2019Afrique n\u2019a jamais eu autant besoin de dirigeants qui voient au-del\u00e0 de leur seul pays, qui b\u00e2tissent pour unir les peuples de ce continent. Vaines sont les touchantes effusions vantant l\u2019int\u00e9gration sous-r\u00e9gionale, si l\u2019on se replie sur soi, l\u00e0 o\u00f9, justement, il faudrait agir ensemble.<\/span><br \/>\n<span style=\"color: #000000;\">Imaginez donc le bel outil que serait une compagnie a\u00e9rienne r\u00e9unissant les quinze pays de la C\u00e9d\u00e9ao, dont l\u2019immense Nigeria, et les six pays de la Cemac, en Afrique centrale\u00a0! Une telle compagnie, confi\u00e9e \u00e0 des professionnels choisis sur le seul crit\u00e8re de la comp\u00e9tence et de la rigueur, et pour peu que la gestion ne soit pas politis\u00e9e, a de bien meilleures chances de succ\u00e8s que les <em>\u00ab\u00a0compagnies de la fiert\u00e9 nationale\u00a0\u00bb.<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Jean-Baptiste Placca<br \/>\n<\/strong>MFI<\/span><\/p>\n<hr \/>\n<p><span style=\"color: #008080;\"><em>* Published in print edition on 24 Feburary 2012<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chronique de Jean-Baptiste Placca<\/p>\n","protected":false},"author":284,"featured_media":6560,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[28],"tags":[4838,20094,7353,20093,20095,19238],"class_list":["post-1526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-world-affairs","tag-air-afrique","tag-air-cote-divoire","tag-air-france-klm","tag-cedeao","tag-cemac","tag-jean-baptiste-placca"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mauritiustimes.com\/mt\/wp-content\/uploads\/2016\/12\/MT-Logokk.jpg?fit=1200%2C880&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QzSF-oC","_links":{"self":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts\/1526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/users\/284"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/comments?post=1526"}],"version-history":[{"count":0,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/posts\/1526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/media\/6560"}],"wp:attachment":[{"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/media?parent=1526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/categories?post=1526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mauritiustimes.com\/mt\/wp-json\/wp\/v2\/tags?post=1526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}